{"id":705,"date":"2022-05-17T15:31:03","date_gmt":"2022-05-17T15:31:03","guid":{"rendered":"https:\/\/www.virtuscomunicacion.com\/?p=705"},"modified":"2022-05-17T15:31:03","modified_gmt":"2022-05-17T15:31:03","slug":"la-agencia-virtus-comunicacion-recibe-el-sello-de-calidad-comunicativa","status":"publish","type":"post","link":"https:\/\/www.virtuscomunicacion.com\/en\/la-agencia-virtus-comunicacion-recibe-el-sello-de-calidad-comunicativa","title":{"rendered":"La agencia Virtus Comunicaci\u00f3n recibe el Sello de Calidad Comunicativa"},"content":{"rendered":"<p>La <strong>agencia de comunicaci\u00f3n de Arag\u00f3n Virtus Comunicaci\u00f3n<\/strong> ha recibido el <strong>Sello de Calidad Comunicativa\u00a0<\/strong>en la categor\u00eda de \u2018Empresa\u2019,\u00a0que por primera vez ha otorgado el\u00a0<a href=\"https:\/\/periodistasdearagon.org\/\" target=\"_blank\" rel=\"noopener\">Colegio Profesional de Periodistas de Arag\u00f3n<\/a>. Se trata de un reconocimiento que han recibido un total de 28 instituciones p\u00fablicas, <strong>empresas de comunicaci\u00f3n<\/strong> y<strong> agencias de comunicaci\u00f3n<\/strong> en reconocimiento a su compromiso por la <strong>excelencia en comunicaci\u00f3n<\/strong> y la transparencia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-706 alignright\" src=\"https:\/\/www.virtuscomunicacion.com\/wp-content\/uploads\/2022\/05\/IMG_5029.jpg\" alt=\"\" width=\"433\" height=\"305\" title=\"\"><\/p>\n<p>La consultora de comunicaci\u00f3n, directora y fundadora de <strong>Virtus Comunicaci\u00f3n<\/strong>, Mercedes Penacho, recogi\u00f3 el sello en el\u00a0acto de entrega que tuvo lugar en\u00a0la Fiesta de los Periodistas, en el Hotel Zaragoza Zentro\u00a0de Zaragoza, este mes de mayo.<\/p>\n<p>Los Sellos de Calidad Comunicativa se han puesto en marcha con el objetivo de incentivar y reconocer la labor de todas aquellas entidades aragonesas que gestionen la comunicaci\u00f3n de su entidad siguiendo criterios de excelencia, contando en sus equipos con profesionales del sector y siguiendo procedimientos transparentes que garanticen la libre concurrencia.<\/p>\n<p>La <strong>agencia de comunicaci\u00f3n de Zaragoza Virtus Comunicaci\u00f3n<\/strong> es una consultora especializada en comunicaci\u00f3n corporativa de empresas e instituciones, con amplia experiencia en asesor\u00eda y ejecuci\u00f3n de planes de comunicaci\u00f3n externa, comunicaci\u00f3n interna, eventos, reputaci\u00f3n y sostenibilidad, relaciones p\u00fablicas y marketing. Ha desarrollado numerosos proyectos en \u00e1mbitos diversos como turismo y cultura, territorio y sostenibilidad, comunicaci\u00f3n de empresa en sectores como el industrial y energ\u00e9tico, as\u00ed como comunicaci\u00f3n de proyectos europeos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-707 aligncenter\" src=\"https:\/\/www.virtuscomunicacion.com\/wp-content\/uploads\/2022\/05\/sello-de-calidad-comunicativa.png\" alt=\"\" width=\"508\" height=\"346\" title=\"\" srcset=\"https:\/\/www.virtuscomunicacion.com\/wp-content\/uploads\/2022\/05\/sello-de-calidad-comunicativa.png 1584w, https:\/\/www.virtuscomunicacion.com\/wp-content\/uploads\/2022\/05\/sello-de-calidad-comunicativa-300x205.png 300w, https:\/\/www.virtuscomunicacion.com\/wp-content\/uploads\/2022\/05\/sello-de-calidad-comunicativa-1024x698.png 1024w, https:\/\/www.virtuscomunicacion.com\/wp-content\/uploads\/2022\/05\/sello-de-calidad-comunicativa-16x12.png 16w\" sizes=\"auto, (max-width: 508px) 100vw, 508px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>La agencia de comunicaci\u00f3n de Arag\u00f3n Virtus Comunicaci\u00f3n ha recibido el Sello de Calidad Comunicativa\u00a0en la categor\u00eda de \u2018Empresa\u2019,\u00a0que por primera vez ha otorgado el\u00a0Colegio Profesional de Periodistas de Arag\u00f3n. Se trata de un reconocimiento que han recibido un total de 28 instituciones p\u00fablicas, empresas de comunicaci\u00f3n y agencias de comunicaci\u00f3n en reconocimiento a su&#8230;<\/p>","protected":false},"author":1,"featured_media":706,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[19,11,31,8,43],"class_list":["post-705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-de-empresa-e-instituciones","tag-agencia-comunicacion-aragon","tag-agencia-comunicacion-zaragoza","tag-comunicacion-corporativa","tag-comunicacion-de-empresa","tag-virtus-comunicacion"],"_links":{"self":[{"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=705"}],"version-history":[{"count":1,"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/705\/revisions"}],"predecessor-version":[{"id":708,"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/705\/revisions\/708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/media\/706"}],"wp:attachment":[{"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virtuscomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}